{"id":6621,"date":"2012-08-04T20:21:00","date_gmt":"2012-08-04T18:21:00","guid":{"rendered":"http:\/\/jblanz.de\/WP\/?p=6621"},"modified":"2021-01-11T00:23:29","modified_gmt":"2021-01-10T23:23:29","slug":"4-august-2012-kuala-lumpur","status":"publish","type":"post","link":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/","title":{"rendered":"4. August 2012 &#8211; Ramadan"},"content":{"rendered":"\n<p>Am Morgen bekamen wir unser Auto und begaben uns auf das erste Abenteuer &#8211; Linksverkehr. Zum ersten Mal sitze ich auf dem Beifahrersitz und habe das Lenkrad vor mit, der Schalthebel ist links von mir und muss mit der linken Hand bedient werden. Wir wollten Richtung Melakka fahren, aber die ganzen vierspurigen Strassen \u00fcberfordern uns und unser Navigationssystem, das wir auf unser Handy geladen haben. Wir fuhren mehrfach falsch, da wir die Ausfahrt zu sp\u00e4t erkannten und mussten lange Umwege machen, um wieder die richtige Strasse zu finden. An einer Ampel bog ich ab und stand direkt vor einer Reihe von Autos, die an der Ampel warteten. Mist, ich war wie im Rechtsverkehr abgebogen. Karin schrie schon, die Autos hupten und die Fahrer winkten erstaunt. Jede Menge Verkehr bis wir endlich die Ausfallstrasse fanden. Mit den Nerven etwas herunter, beschlossen wir m\u00f6glichst bald ein Hotel anzusteuern. Leider hatten wir in Melakka f\u00fcr heute Samstag kein Zimmer gefunden, das unsere Anspr\u00fcche erf\u00fcllt h\u00e4tte. Deshalb hatten wir via Booking.com ein Hotel etwas ausserhalb gebucht. Wir folgten den Angaben in Booking.com und kamen kurz nach Mittag am Ziel an. Aber das Hotel war nirgends zu finden und im Internet war das Hotel auch nicht besser beschrieben. Wir fuhren mehrfach alle Strassen ringsum ab, aber keine Spur des Hotels. Irgendwann gaben wir auf und fragten die Polizei, die mit ihren Motorr\u00e4dern am Strassenrand stand, um den Verkehr zu kontrollieren. Sie waren sehr freundlich und machten uns klar, dass wir dieses Hotel wohl alleine nicht finden w\u00fcrden. Aber sie w\u00fcrden uns hinbringen. So bekamen wir eine Polizeieskorte und tats\u00e4chlich nach ca 30 km bogen sie rechts ab und zeigten auf das Hotel, das wir gebucht hatten. WIr bedankten uns f\u00fcr ihre Hilfe &#8211; gar nicht so einfach, da sie kein Wort englisch sprachen. Das Hotel war ein relativ neues Haus, das vorzugsweise f\u00fcr asiatische G\u00e4ste erbaut war. Unsere Beschwerde, dass die Koordination in Booking.com v\u00f6llig falsch sind, bewirkte nur Achselzucken.<\/p>\n<p>Als wir fragten, wo das Restaurant w\u00e4re, bekamen wir nur ein Bedauern &#8211; Ramadan bis zum 18. August. Restaurant geschlossen, aber wir k\u00f6nnten nach Sonnenuntergang, also um ca 19.30 Uhr, beim gemeinsamen Essen mitmachen. Erst dachten wir, dass es sich nicht schickt, wenn Christen zum muslimischen Fastenbrechen gehen, aber der Hunger siegte und wir meldeten uns an. Da wir nicht einsch\u00e4tzen konnten, ob vielleicht Gebete vor dem Essen stattfinden, gingen wir erst gegen 20 Uhr runter. Das Essen war bereits voll im Gange und das Buffet war schon fast leer. Der ganze Garten war voller Menschen und jeder hatte einen Teller vollgeh\u00e4uft mit jeder Menge Essen vor sich stehen und mampfte vor sich hin. Ein Musikgruppe sang und spielte f\u00fcr uns merkw\u00fcrdige Weisen. Es war irgendwie eine traurige Stimmung. Niemand sprach miteinander.<\/p>\n<p>Als wir reinkamen, sprangen sofort ein paar M\u00e4nner auf und waren \u00fcberaus freundlich zu uns. Sie h\u00e4tten f\u00fcr uns die besten St\u00fccke Lammfleisch zur\u00fcckbehalten. Wir sollten uns setzen, sie w\u00fcrden uns helfen und bedienen. Diese Gastfreundschaft hat uns sehr \u00fcberrascht, das h\u00e4tten wir nicht gedacht. Wer in Deutschland w\u00fcrde sich um Muslime k\u00fcmmern, die in ein Restaurant kommen und nicht wissen, was zu tun ist ? Wie schon gesagt, war das Buffet mehr oder weniger leergefegt und das &#8222;beste&#8220; Lammfleisch war leider auch ziemlich z\u00e4h. Wir a\u00dfen also die Reste ohne wirklich satt zu werden. Zu Trinken gab es auch nur Wasser und Fruchts\u00e4fte. Inzwischen hatte sich die Gesellschaft auch mehr oder weniger aufgel\u00f6st. Wir wunderten uns anfangs, dass mehrere Busse vor dem Hotel standen. Diese Busse brachten wohl nur die Menschen zum Abendessen nach Sonnenuntergang und anschliessend wieder nach Hause.<\/p>\n<p>Eine Erfahrung reicher gingen wir nach einer Stunde auf unser Zimmer. Der Ramadan begleitete uns von nun ab auf all unseren Hotelaufenthalten in Malaysia und die Anreise per Bus konnten wir \u00f6fter beobachten. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg\" alt=\"\" data-id=\"6656\" data-full-url=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg\" data-link=\"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/malaysia_518\/\" class=\"wp-image-6656\" srcset=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg 800w, https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518-300x169.jpg 300w, https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_520.jpg\" alt=\"\" data-id=\"6657\" data-full-url=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_520.jpg\" data-link=\"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/malaysia_520\/\" class=\"wp-image-6657\" srcset=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_520.jpg 800w, https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_520-300x169.jpg 300w, https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_520-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Am Morgen bekamen wir unser Auto und begaben uns auf das erste Abenteuer &#8211; Linksverkehr. Zum ersten Mal sitze ich<\/p>\n","protected":false},"author":1,"featured_media":6656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[212,28,24],"tags":[],"class_list":["post-6621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-212","category-asien","category-malaysia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4. August 2012 - Ramadan - Reiseblog von Karin &amp; Joachim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4. August 2012 - Ramadan - Reiseblog von Karin &amp; Joachim\" \/>\n<meta property=\"og:description\" content=\"Am Morgen bekamen wir unser Auto und begaben uns auf das erste Abenteuer &#8211; Linksverkehr. Zum ersten Mal sitze ich\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/\" \/>\n<meta property=\"og:site_name\" content=\"Reiseblog von Karin &amp; Joachim\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-04T18:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-10T23:23:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Achim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Achim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/\"},\"author\":{\"name\":\"Achim\",\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/#\\\/schema\\\/person\\\/17a70f07162e42bc0b181c22397286e0\"},\"headline\":\"4. August 2012 &#8211; Ramadan\",\"datePublished\":\"2012-08-04T18:21:00+00:00\",\"dateModified\":\"2021-01-10T23:23:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/\"},\"wordCount\":665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/#\\\/schema\\\/person\\\/17a70f07162e42bc0b181c22397286e0\"},\"image\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Malaysia_518.jpg\",\"articleSection\":[\"2012\",\"Asien\",\"Malaysia\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/\",\"url\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/\",\"name\":\"4. August 2012 - Ramadan - Reiseblog von Karin &amp; Joachim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Malaysia_518.jpg\",\"datePublished\":\"2012-08-04T18:21:00+00:00\",\"dateModified\":\"2021-01-10T23:23:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Malaysia_518.jpg\",\"contentUrl\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Malaysia_518.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/4-august-2012-kuala-lumpur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4. August 2012 &#8211; Ramadan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/#website\",\"url\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/\",\"name\":\"Reiseblog von Karin & Joachim\",\"description\":\"Wir schreiben den Blog f\u00fcr uns als Erinnerung - f\u00fcr euch als Inspiration\",\"publisher\":{\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/#\\\/schema\\\/person\\\/17a70f07162e42bc0b181c22397286e0\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/#\\\/schema\\\/person\\\/17a70f07162e42bc0b181c22397286e0\",\"name\":\"Achim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g\",\"caption\":\"Achim\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g\"},\"url\":\"https:\\\/\\\/jblanz.de\\\/WP\\\/author\\\/achim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4. August 2012 - Ramadan - Reiseblog von Karin &amp; Joachim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/","og_locale":"de_DE","og_type":"article","og_title":"4. August 2012 - Ramadan - Reiseblog von Karin &amp; Joachim","og_description":"Am Morgen bekamen wir unser Auto und begaben uns auf das erste Abenteuer &#8211; Linksverkehr. Zum ersten Mal sitze ich","og_url":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/","og_site_name":"Reiseblog von Karin &amp; Joachim","article_published_time":"2012-08-04T18:21:00+00:00","article_modified_time":"2021-01-10T23:23:29+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg","type":"image\/jpeg"}],"author":"Achim","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Achim","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#article","isPartOf":{"@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/"},"author":{"name":"Achim","@id":"https:\/\/jblanz.de\/WP\/#\/schema\/person\/17a70f07162e42bc0b181c22397286e0"},"headline":"4. August 2012 &#8211; Ramadan","datePublished":"2012-08-04T18:21:00+00:00","dateModified":"2021-01-10T23:23:29+00:00","mainEntityOfPage":{"@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/"},"wordCount":665,"commentCount":0,"publisher":{"@id":"https:\/\/jblanz.de\/WP\/#\/schema\/person\/17a70f07162e42bc0b181c22397286e0"},"image":{"@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#primaryimage"},"thumbnailUrl":"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg","articleSection":["2012","Asien","Malaysia"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/","url":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/","name":"4. August 2012 - Ramadan - Reiseblog von Karin &amp; Joachim","isPartOf":{"@id":"https:\/\/jblanz.de\/WP\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#primaryimage"},"image":{"@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#primaryimage"},"thumbnailUrl":"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg","datePublished":"2012-08-04T18:21:00+00:00","dateModified":"2021-01-10T23:23:29+00:00","breadcrumb":{"@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#primaryimage","url":"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg","contentUrl":"https:\/\/jblanz.de\/WP\/wp-content\/uploads\/2021\/01\/Malaysia_518.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/jblanz.de\/WP\/4-august-2012-kuala-lumpur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/jblanz.de\/WP\/"},{"@type":"ListItem","position":2,"name":"4. August 2012 &#8211; Ramadan"}]},{"@type":"WebSite","@id":"https:\/\/jblanz.de\/WP\/#website","url":"https:\/\/jblanz.de\/WP\/","name":"Reiseblog von Karin & Joachim","description":"Wir schreiben den Blog f\u00fcr uns als Erinnerung - f\u00fcr euch als Inspiration","publisher":{"@id":"https:\/\/jblanz.de\/WP\/#\/schema\/person\/17a70f07162e42bc0b181c22397286e0"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jblanz.de\/WP\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/jblanz.de\/WP\/#\/schema\/person\/17a70f07162e42bc0b181c22397286e0","name":"Achim","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g","caption":"Achim"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/b7ab31bc55956af4a9bebf7fd034761212b11b803b7e39464914d6abeefb12f3?s=96&d=mm&r=g"},"url":"https:\/\/jblanz.de\/WP\/author\/achim\/"}]}},"_links":{"self":[{"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/posts\/6621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/comments?post=6621"}],"version-history":[{"count":0,"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/posts\/6621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/media\/6656"}],"wp:attachment":[{"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/media?parent=6621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/categories?post=6621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jblanz.de\/WP\/wp-json\/wp\/v2\/tags?post=6621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}